{"id":284,"date":"2023-11-09T14:28:17","date_gmt":"2023-11-09T13:28:17","guid":{"rendered":"https:\/\/serwer1391483.home.pl\/nowa\/index.php\/home-copy\/"},"modified":"2024-01-16T23:36:24","modified_gmt":"2024-01-16T22:36:24","slug":"homepage","status":"publish","type":"page","link":"https:\/\/aquaseen.pl\/","title":{"rendered":"Homepage"},"content":{"rendered":"<div id='full_slider_1'  class='avia-fullwidth-slider main_color avia-shadow   avia-builder-el-0  el_before_av_section  avia-builder-el-first   container_wrap sidebar_right'  >\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ccisj0-4f27b4b920597e0ea98616c1a37e272a\">\n@keyframes av_slideshow_img_scale_av-ccisj0-4f27b4b920597e0ea98616c1a37e272a {\n   0% { transform: scale(1.2); opacity: 1; }\n 100% { transform: scale(1.03); opacity: 1; }\n}\n.avia-slideshow.av-ccisj0-4f27b4b920597e0ea98616c1a37e272a .avia-slideshow-slide.next-active-slide img{\nanimation:av_slideshow_img_scale_av-ccisj0-4f27b4b920597e0ea98616c1a37e272a 15s 1 ease-in-out;\ntransform:scale(1.03);\nopacity:1;\n}\n<\/style>\n<div  class='avia-slideshow av-ccisj0-4f27b4b920597e0ea98616c1a37e272a avia-slideshow-featured_large av_slideshow_full avia-fade-slider av-slideshow-ui av-control-minimal av-nav-dots-visible av-slideshow-autoplay av-loop-endless av-loop-manual-endless av-default-height-applied   avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;fade&quot;,&quot;autoplay&quot;:true,&quot;loop_autoplay&quot;:&quot;endless&quot;,&quot;interval&quot;:10,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 49.21875%;'><li  class='avia-slideshow-slide av-ccisj0-4f27b4b920597e0ea98616c1a37e272a__0  slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><div class='av-slideshow-caption av-ccisj0-4f27b4b920597e0ea98616c1a37e272a__0 caption_fullwidth caption_center'><div class=\"container caption_container\"><div class=\"slideshow_caption\"><div class=\"slideshow_inner_caption\"><div class=\"slideshow_align_caption\"><h2 class='avia-caption-title '  itemprop=\"name\" >Od koncepcji do utrzymania<\/h2><br\/><a href='https:\/\/aquaseen.pl\/index.php\/oferta\/'  class='avia-slideshow-button avia-button avia-color-theme-color avia-multi-slideshow-button' data-duration='800' data-easing='easeInOutQuad'>Oferta<\/a><a href='https:\/\/aquaseen.pl\/index.php\/kontakt\/'  class='avia-slideshow-button avia-button avia-color-light avia-multi-slideshow-button avia-slideshow-button-2' data-duration='800' data-easing='easeInOutQuad'>Zadaj pytanie<\/a><\/div><\/div><\/div><\/div><\/div><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-333 avia-img-lazy-loading-not-333\"  src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/water-6122257_1280-1280x630.jpg\" width=\"1280\" height=\"630\" title='water-6122257_1280' alt=''  itemprop=\"thumbnailUrl\"   \/><div class='av-section-color-overlay' style='opacity: 0.3; background-color: #000000; '><\/div><\/div><\/li><li  class='avia-slideshow-slide av-ccisj0-4f27b4b920597e0ea98616c1a37e272a__1  slide-2 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><div class='av-slideshow-caption av-ccisj0-4f27b4b920597e0ea98616c1a37e272a__1 caption_fullwidth caption_left'><div class=\"container caption_container\"><div class=\"slideshow_caption\"><div class=\"slideshow_inner_caption\"><div class=\"slideshow_align_caption\"><h2 class='avia-caption-title '  itemprop=\"name\" >Zesp\u00f3\u0142 wykwalifikowanych specjalist\u00f3w<\/h2><br\/><a href='https:\/\/aquaseen.pl\/index.php\/o-nas\/'  class='avia-slideshow-button avia-button avia-color-light ' data-duration='800' data-easing='easeInOutQuad'>O nas<\/a><\/div><\/div><\/div><\/div><\/div><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-332 avia-img-lazy-loading-not-332\"  src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/workplace-health-and-safety-1500x630.webp\" width=\"1500\" height=\"630\" title='workplace-health-and-safety' alt=''  itemprop=\"thumbnailUrl\"   \/><div class='av-section-color-overlay' style='opacity: 0.2; background-color: #0a0a0a; '><\/div><\/div><\/li><li  class='avia-slideshow-slide av-ccisj0-4f27b4b920597e0ea98616c1a37e272a__2  slide-3 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><div class='av-slideshow-caption av-ccisj0-4f27b4b920597e0ea98616c1a37e272a__2 caption_fullwidth caption_right'><div class=\"container caption_container\"><div class=\"slideshow_caption\"><div class=\"slideshow_inner_caption\"><div class=\"slideshow_align_caption\"><h2 class='avia-caption-title '  itemprop=\"name\" >Do\u015bwiadczenie<\/h2><br\/><a href='https:\/\/aquaseen.pl\/index.php\/realizacje\/'  class='avia-slideshow-button avia-button avia-color-theme-color ' data-duration='800' data-easing='easeInOutQuad'>Realizacje<\/a><\/div><\/div><\/div><\/div><\/div><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-331 avia-img-lazy-loading-not-331\"  src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/SE-PREF-1500x630.jpg\" width=\"1500\" height=\"630\" title='SE-PREF' alt=''  itemprop=\"thumbnailUrl\"   \/><div class='av-section-color-overlay' style='opacity: 0.3; background-color: #0a0a0a; '><\/div><\/div><\/li><\/ul><div class='avia-slideshow-arrows avia-slideshow-controls' ><a href='#prev' class='prev-slide ' aria-hidden='true' data-av_icon='\ue87c' data-av_iconfont='entypo-fontello'  tabindex='-1'>Previous<\/a><a href='#next' class='next-slide ' aria-hidden='true' data-av_icon='\ue87d' data-av_iconfont='entypo-fontello'  tabindex='-1'>Next<\/a><\/div><div class='avia-slideshow-dots avia-slideshow-controls'><a href='#1' class='goto-slide active' >1<\/a><a href='#2' class='goto-slide ' >2<\/a><a href='#3' class='goto-slide ' >3<\/a><\/div><\/div><\/div>\n<div id='av_section_1'  class='avia-section av-b04yic-dc1759bd1907f1a8227b5af35f958548 alternate_color avia-section-large avia-no-border-styling  avia-builder-el-1  el_after_av_slideshow_full  el_before_av_section  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-284'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-au0cdo-52d28308ce389d92ffd0303595823e44\">\n#top .av-special-heading.av-au0cdo-52d28308ce389d92ffd0303595823e44{\npadding-bottom:0;\n}\nbody .av-special-heading.av-au0cdo-52d28308ce389d92ffd0303595823e44 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-au0cdo-52d28308ce389d92ffd0303595823e44 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-au0cdo-52d28308ce389d92ffd0303595823e44 av-special-heading-h2 blockquote modern-quote modern-centered  avia-builder-el-2  el_before_av_hr  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Obszary Dzia\u0142ania<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-am4l3o-171d217f5174a34b65d7ed332f232d10\">\n#top .hr.av-am4l3o-171d217f5174a34b65d7ed332f232d10{\nmargin-top:5px;\nmargin-bottom:35px;\n}\n.hr.av-am4l3o-171d217f5174a34b65d7ed332f232d10 .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-am4l3o-171d217f5174a34b65d7ed332f232d10 hr-custom  avia-builder-el-3  el_after_av_heading  el_before_av_one_third  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ak5xw4-8b1243f8105d6bb44770e883082c7db3\">\n.flex_column.av-ak5xw4-8b1243f8105d6bb44770e883082c7db3{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-ak5xw4-8b1243f8105d6bb44770e883082c7db3 av_one_third  avia-builder-el-4  el_after_av_hr  el_before_av_one_third  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-abm2k4-efac339bfce8f29a7bdc8c8e1e6a1665\">\n.avia-image-container.av-abm2k4-efac339bfce8f29a7bdc8c8e1e6a1665 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-abm2k4-efac339bfce8f29a7bdc8c8e1e6a1665 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-abm2k4-efac339bfce8f29a7bdc8c8e1e6a1665 av-styling-circle avia-align-center  avia-builder-el-5  el_before_av_heading  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-363 avia-img-lazy-loading-not-363 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.05-PM-180x180.png\" alt='' title='Zrzut ekranu 2023-11-16 o 11.22.05 PM'  height=\"180\" width=\"180\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.05-PM-180x180.png 180w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.05-PM-298x300.png 298w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.05-PM-80x80.png 80w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.05-PM-36x36.png 36w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.05-PM.png 600w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-a6x2gc-36fb09b585e0236cd6ce7087dfe92244\">\n#top .av-special-heading.av-a6x2gc-36fb09b585e0236cd6ce7087dfe92244{\npadding-bottom:0;\n}\nbody .av-special-heading.av-a6x2gc-36fb09b585e0236cd6ce7087dfe92244 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-a6x2gc-36fb09b585e0236cd6ce7087dfe92244 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-a6x2gc-36fb09b585e0236cd6ce7087dfe92244 av-special-heading-h3 blockquote modern-quote modern-centered  avia-builder-el-6  el_after_av_image  avia-builder-el-last '><h3 class='av-special-heading-tag'  itemprop=\"headline\"  >Woda Pitna<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-9r9d8s-2f7d863e31673847d23446f94666756e\">\n.flex_column.av-9r9d8s-2f7d863e31673847d23446f94666756e{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-9r9d8s-2f7d863e31673847d23446f94666756e av_one_third  avia-builder-el-7  el_after_av_one_third  el_before_av_one_third  flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-9hkcfg-1551fb58db71e7df0c9486ba45712b24\">\n.avia-image-container.av-9hkcfg-1551fb58db71e7df0c9486ba45712b24 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-9hkcfg-1551fb58db71e7df0c9486ba45712b24 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-9hkcfg-1551fb58db71e7df0c9486ba45712b24 av-styling-circle avia-align-center  avia-builder-el-8  el_before_av_heading  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-362 avia-img-lazy-loading-not-362 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.25-PM-180x180.png\" alt='' title='Zrzut ekranu 2023-11-16 o 11.22.25 PM'  height=\"180\" width=\"180\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.25-PM-180x180.png 180w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.25-PM-298x300.png 298w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.25-PM-80x80.png 80w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.25-PM-36x36.png 36w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.25-PM.png 600w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-9dcns4-456699fe2c390a79c22529270d5c72cd\">\n#top .av-special-heading.av-9dcns4-456699fe2c390a79c22529270d5c72cd{\npadding-bottom:0;\n}\nbody .av-special-heading.av-9dcns4-456699fe2c390a79c22529270d5c72cd .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-9dcns4-456699fe2c390a79c22529270d5c72cd .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-9dcns4-456699fe2c390a79c22529270d5c72cd av-special-heading-h3 blockquote modern-quote modern-centered  avia-builder-el-9  el_after_av_image  avia-builder-el-last '><h3 class='av-special-heading-tag'  itemprop=\"headline\"  >Woda dla cel\u00f3w przemys\u0142owych<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-8skbys-40a3dd0612cdab45ac797198b69117ff\">\n.flex_column.av-8skbys-40a3dd0612cdab45ac797198b69117ff{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-8skbys-40a3dd0612cdab45ac797198b69117ff av_one_third  avia-builder-el-10  el_after_av_one_third  avia-builder-el-last  flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-8pdj90-6afc80f5ca166e57ab800b19cf16bb9c\">\n.avia-image-container.av-8pdj90-6afc80f5ca166e57ab800b19cf16bb9c img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-8pdj90-6afc80f5ca166e57ab800b19cf16bb9c .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-8pdj90-6afc80f5ca166e57ab800b19cf16bb9c av-styling-circle avia-align-center  avia-builder-el-11  el_before_av_heading  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-361 avia-img-lazy-loading-not-361 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.38-PM-180x180.png\" alt='' title='Zrzut ekranu 2023-11-16 o 11.22.38 PM'  height=\"180\" width=\"180\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.38-PM-180x180.png 180w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.38-PM-298x300.png 298w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.38-PM-80x80.png 80w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.38-PM-36x36.png 36w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/Zrzut-ekranu-2023-11-16-o-11.22.38-PM.png 600w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-8jx518-a1be964cc6845ac443cad20f33134edb\">\n#top .av-special-heading.av-8jx518-a1be964cc6845ac443cad20f33134edb{\npadding-bottom:0;\n}\nbody .av-special-heading.av-8jx518-a1be964cc6845ac443cad20f33134edb .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-8jx518-a1be964cc6845ac443cad20f33134edb .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-8jx518-a1be964cc6845ac443cad20f33134edb av-special-heading-h3 blockquote modern-quote modern-centered  avia-builder-el-12  el_after_av_image  avia-builder-el-last '><h3 class='av-special-heading-tag'  itemprop=\"headline\"  >\u015acieki<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5erepo-dc74054437fc0939d4a65f3c7a716034\">\n.avia-section.av-5erepo-dc74054437fc0939d4a65f3c7a716034 .av-parallax .av-parallax-inner{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/output-1.png);\nbackground-position:50% 0%;\nbackground-attachment:scroll;\n}\n<\/style>\n<div id='av_section_2'  class='avia-section av-5erepo-dc74054437fc0939d4a65f3c7a716034 alternate_color avia-section-large avia-no-border-styling  avia-builder-el-13  el_after_av_section  el_before_av_section  avia-full-stretch av-parallax-section avia-bg-style-parallax container_wrap sidebar_right'  data-section-bg-repeat='stretch'><div class='av-parallax' data-avia-parallax-ratio='0.3' ><div class='av-parallax-inner alternate_color avia-full-stretch'><\/div><\/div><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-284'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-586rf8-48b8bd4089e3d722bb84fe8718a49f28\">\n#top .av-special-heading.av-586rf8-48b8bd4089e3d722bb84fe8718a49f28{\npadding-bottom:0;\n}\nbody .av-special-heading.av-586rf8-48b8bd4089e3d722bb84fe8718a49f28 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-586rf8-48b8bd4089e3d722bb84fe8718a49f28 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-586rf8-48b8bd4089e3d722bb84fe8718a49f28 av-special-heading-h2 blockquote modern-quote modern-centered  avia-builder-el-14  el_before_av_hr  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Co nas wyr\u00f3\u017cnia?<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-50vikk-5868ff252836751a3f2c512fecdc46d9\">\n#top .hr.av-50vikk-5868ff252836751a3f2c512fecdc46d9{\nmargin-top:5px;\nmargin-bottom:35px;\n}\n.hr.av-50vikk-5868ff252836751a3f2c512fecdc46d9 .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-50vikk-5868ff252836751a3f2c512fecdc46d9 hr-custom  avia-builder-el-15  el_after_av_heading  el_before_av_one_third  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4mc4r0-1e8a96b6a6e785548e7359a0ed0ec8ed\">\n#top .flex_column.av-4mc4r0-1e8a96b6a6e785548e7359a0ed0ec8ed{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n.flex_column.av-4mc4r0-1e8a96b6a6e785548e7359a0ed0ec8ed{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n.responsive #top #wrap_all .flex_column.av-4mc4r0-1e8a96b6a6e785548e7359a0ed0ec8ed{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n<\/style>\n<div  class='flex_column av-4mc4r0-1e8a96b6a6e785548e7359a0ed0ec8ed av_one_third  avia-builder-el-16  el_after_av_hr  el_before_av_one_third  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  '     ><article  class='iconbox iconbox_top av-4ewarw-a75910eb4db8a9849e3792ec22404b7b av-no-box  avia-builder-el-17  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\"><div class=\"iconbox_icon heading-color\" aria-hidden='true' data-av_icon='\ue8cd' data-av_iconfont='entypo-fontello'><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" >Ponad 55 lat istnienia na rynku<\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-wya8k-212c133cd6b34f16d5b5aed1fedd1b6e\">\n#top .flex_column.av-wya8k-212c133cd6b34f16d5b5aed1fedd1b6e{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n.flex_column.av-wya8k-212c133cd6b34f16d5b5aed1fedd1b6e{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n.responsive #top #wrap_all .flex_column.av-wya8k-212c133cd6b34f16d5b5aed1fedd1b6e{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n<\/style>\n<div  class='flex_column av-wya8k-212c133cd6b34f16d5b5aed1fedd1b6e av_one_third  avia-builder-el-18  el_after_av_one_third  el_before_av_one_third  flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  '     ><article  class='iconbox iconbox_top av-lp1rqxb6-6117887884cd35bb0212ff98a0991ca3 av-no-box  avia-builder-el-19  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\"><div class=\"iconbox_icon heading-color\" aria-hidden='true' data-av_icon='\ue8cd' data-av_iconfont='entypo-fontello'><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" >Do\u015bwiadczony zesp\u00f3\u0142<\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><p>Projektant\u00f3w i technolog\u00f3w<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2xjlo-afb1c78808982b938f59e8b9a4878b22\">\n#top .flex_column.av-2xjlo-afb1c78808982b938f59e8b9a4878b22{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n.flex_column.av-2xjlo-afb1c78808982b938f59e8b9a4878b22{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n.responsive #top #wrap_all .flex_column.av-2xjlo-afb1c78808982b938f59e8b9a4878b22{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n<\/style>\n<div  class='flex_column av-2xjlo-afb1c78808982b938f59e8b9a4878b22 av_one_third  avia-builder-el-20  el_after_av_one_third  el_before_av_one_third  flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  '     ><article  class='iconbox iconbox_top av-lp1rn937-e7cffbfe76dbf37ce5fc841ac115d892 av-no-box  avia-builder-el-21  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\"><div class=\"iconbox_icon heading-color\" aria-hidden='true' data-av_icon='\ue8cd' data-av_iconfont='entypo-fontello'><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" >W\u0142asne opracowania i patenty<\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-n1fsc-3375026ae73c178bf8e146052d6a1cf9\">\n#top .flex_column.av-n1fsc-3375026ae73c178bf8e146052d6a1cf9{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n.flex_column.av-n1fsc-3375026ae73c178bf8e146052d6a1cf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n.responsive #top #wrap_all .flex_column.av-n1fsc-3375026ae73c178bf8e146052d6a1cf9{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n<\/style>\n<div  class='flex_column av-n1fsc-3375026ae73c178bf8e146052d6a1cf9 av_one_third  avia-builder-el-22  el_after_av_one_third  el_before_av_one_third  first flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><article  class='iconbox iconbox_top av-lp1rnjj2-41638fa0d012234795a47a0ea6cd038b av-no-box  avia-builder-el-23  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\"><div class=\"iconbox_icon heading-color\" aria-hidden='true' data-av_icon='\ue8cd' data-av_iconfont='entypo-fontello'><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" >Blisko 1500 realizacji<\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-h0264-0dcb0f3952f3ff696acdaf996194ea07\">\n#top .flex_column.av-h0264-0dcb0f3952f3ff696acdaf996194ea07{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n.flex_column.av-h0264-0dcb0f3952f3ff696acdaf996194ea07{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n.responsive #top #wrap_all .flex_column.av-h0264-0dcb0f3952f3ff696acdaf996194ea07{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n<\/style>\n<div  class='flex_column av-h0264-0dcb0f3952f3ff696acdaf996194ea07 av_one_third  avia-builder-el-24  el_after_av_one_third  el_before_av_one_third  flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><article  class='iconbox iconbox_top av-lp1rnu3c-438393894ef016516ec172e721de029c av-no-box  avia-builder-el-25  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\"><div class=\"iconbox_icon heading-color\" aria-hidden='true' data-av_icon='\ue8cd' data-av_iconfont='entypo-fontello'><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" >Szeroki zakres wykonawstwa<\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><p>Instalacje sanitarne, mechaniczne, elektryczna, AKPiA<\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-8uvdw-eb0eda85a01a2b5772c95a3ad0f53814\">\n#top .flex_column.av-8uvdw-eb0eda85a01a2b5772c95a3ad0f53814{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n.flex_column.av-8uvdw-eb0eda85a01a2b5772c95a3ad0f53814{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n.responsive #top #wrap_all .flex_column.av-8uvdw-eb0eda85a01a2b5772c95a3ad0f53814{\nmargin-top:0px;\nmargin-bottom:0px;\n}\n<\/style>\n<div  class='flex_column av-8uvdw-eb0eda85a01a2b5772c95a3ad0f53814 av_one_third  avia-builder-el-26  el_after_av_one_third  avia-builder-el-last  flex_column_div av-animated-generic bottom-to-top av-zero-column-padding  column-top-margin'     ><article  class='iconbox iconbox_top av-lp1rob1d-26056280321bd57fd920e574338186d2 av-no-box  avia-builder-el-27  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\"><div class=\"iconbox_icon heading-color\" aria-hidden='true' data-av_icon='\ue8cd' data-av_iconfont='entypo-fontello'><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" >W\u0142asna grupa rozruchowa i serwis<\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<\/p>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_3'  class='avia-section av-lor9vl7y-7476782a4a06a2605837fda46a642d41 main_color avia-section-large avia-no-border-styling  avia-builder-el-28  el_after_av_section  el_before_av_section  avia-bg-style-parallax container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-284'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lor8jv8x-96daab34e224daed8c3b3b8588ce4e1d\">\n#top .av-special-heading.av-lor8jv8x-96daab34e224daed8c3b3b8588ce4e1d{\npadding-bottom:0;\n}\nbody .av-special-heading.av-lor8jv8x-96daab34e224daed8c3b3b8588ce4e1d .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-lor8jv8x-96daab34e224daed8c3b3b8588ce4e1d .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-lor8jv8x-96daab34e224daed8c3b3b8588ce4e1d av-special-heading-h2 blockquote modern-quote modern-centered  avia-builder-el-29  el_before_av_hr  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Zaufali nam<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-yphp8-e4982b1ba9b236a77db5f58e81d98cb8\">\n#top .hr.av-yphp8-e4982b1ba9b236a77db5f58e81d98cb8{\nmargin-top:5px;\nmargin-bottom:35px;\n}\n.hr.av-yphp8-e4982b1ba9b236a77db5f58e81d98cb8 .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-yphp8-e4982b1ba9b236a77db5f58e81d98cb8 hr-custom  avia-builder-el-30  el_after_av_heading  el_before_av_one_third  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div class='flex_column_table av-lpix2se7-972eb61dd0d3e1f690132c04c85ad3bb sc-av_one_third av-equal-height-column-flextable'><div  class='flex_column av-lpix2se7-972eb61dd0d3e1f690132c04c85ad3bb av_one_third  avia-builder-el-31  el_after_av_hr  el_before_av_one_third  first flex_column_table_cell av-equal-height-column av-align-middle  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lpix0slt-eca372ee59c0ab3910fc64b59e629079\">\n.avia-image-container.av-lpix0slt-eca372ee59c0ab3910fc64b59e629079 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-lpix0slt-eca372ee59c0ab3910fc64b59e629079 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-lpix0slt-eca372ee59c0ab3910fc64b59e629079 av-styling- avia-align-center  avia-builder-el-32  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-480 avia-img-lazy-loading-not-480 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-wodociagi-wroclaw-300x87.png\" alt='' title='klient wodocia\u0328gi wroc\u0142aw'  height=\"87\" width=\"300\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-wodociagi-wroclaw-300x87.png 300w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-wodociagi-wroclaw.png 417w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/div><\/div><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-3c2rtg-8c68cca3970c3dbc587176815523c536 av_one_third  avia-builder-el-33  el_after_av_one_third  el_before_av_one_third  flex_column_table_cell av-equal-height-column av-align-middle  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lpix21eq-67dc1310697afb4c403701b4d6514a48\">\n.avia-image-container.av-lpix21eq-67dc1310697afb4c403701b4d6514a48 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-lpix21eq-67dc1310697afb4c403701b4d6514a48 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-lpix21eq-67dc1310697afb4c403701b4d6514a48 av-styling- avia-align-center  avia-builder-el-34  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-479 avia-img-lazy-loading-not-479 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-wodociagi-Warszawa.png\" alt='' title='klient wodocia\u0328gi Warszawa'  height=\"100\" width=\"222\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-36zx98-be99a22e3051d57afd84b9e1b797e7ee av_one_third  avia-builder-el-35  el_after_av_one_third  el_before_av_one_third  flex_column_table_cell av-equal-height-column av-align-middle  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lpix1tcc-fa0dd7599f1dc31736bc8e6ff2ff7500\">\n.avia-image-container.av-lpix1tcc-fa0dd7599f1dc31736bc8e6ff2ff7500 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-lpix1tcc-fa0dd7599f1dc31736bc8e6ff2ff7500 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-lpix1tcc-fa0dd7599f1dc31736bc8e6ff2ff7500 av-styling- avia-align-center  avia-builder-el-36  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-478 avia-img-lazy-loading-not-478 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-wodociagi-Krakow-300x134.png\" alt='' title='klient wodocia\u0328gi Krako\u0301w'  height=\"134\" width=\"300\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-wodociagi-Krakow-300x134.png 300w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-wodociagi-Krakow.png 337w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/div><\/div><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><div class='flex_column_table av-30ykes-756aa6e0acfa5cda4f20a520a37329df sc-av_one_third av-equal-height-column-flextable'><div  class='flex_column av-30ykes-756aa6e0acfa5cda4f20a520a37329df av_one_third  avia-builder-el-37  el_after_av_one_third  el_before_av_one_third  first flex_column_table_cell av-equal-height-column av-align-middle  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lpix5zgf-d1d229f80d5fe13b48d36b8baf376520\">\n.avia-image-container.av-lpix5zgf-d1d229f80d5fe13b48d36b8baf376520 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-lpix5zgf-d1d229f80d5fe13b48d36b8baf376520 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-lpix5zgf-d1d229f80d5fe13b48d36b8baf376520 av-styling- avia-align-center  avia-builder-el-38  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-477 avia-img-lazy-loading-not-477 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-wodociagi-bialystok.png\" alt='' title='klient wodocia\u0328gi bia\u0142ystok'  height=\"226\" width=\"223\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-wodociagi-bialystok.png 223w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-wodociagi-bialystok-80x80.png 80w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-wodociagi-bialystok-36x36.png 36w\" sizes=\"(max-width: 223px) 100vw, 223px\" \/><\/div><\/div><\/div><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-2wnuys-996c999894604de30e52b2f7e48e1d98 av_one_third  avia-builder-el-39  el_after_av_one_third  el_before_av_one_third  flex_column_table_cell av-equal-height-column av-align-middle  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lpix68px-2eb80dc20aba23cefab151d7641e7c0e\">\n.avia-image-container.av-lpix68px-2eb80dc20aba23cefab151d7641e7c0e img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-lpix68px-2eb80dc20aba23cefab151d7641e7c0e .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-lpix68px-2eb80dc20aba23cefab151d7641e7c0e av-styling- avia-align-center  avia-builder-el-40  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-475 avia-img-lazy-loading-not-475 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-mahle-300x66.png\" alt='' title='klient mahle'  height=\"66\" width=\"300\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-mahle-300x66.png 300w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-mahle.png 478w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/div><\/div><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-2rdg10-48885054ace61a42d1f60513450a916b av_one_third  avia-builder-el-41  el_after_av_one_third  el_before_av_one_third  flex_column_table_cell av-equal-height-column av-align-middle  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lpix6ggl-e37026677bcac2da0e39410411ce749e\">\n.avia-image-container.av-lpix6ggl-e37026677bcac2da0e39410411ce749e img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-lpix6ggl-e37026677bcac2da0e39410411ce749e .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-lpix6ggl-e37026677bcac2da0e39410411ce749e av-styling- avia-align-center  avia-builder-el-42  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-474 avia-img-lazy-loading-not-474 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-grupa-azoty-police.png\" alt='' title='klient grupa azoty police'  height=\"225\" width=\"225\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-grupa-azoty-police.png 225w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-grupa-azoty-police-80x80.png 80w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-grupa-azoty-police-36x36.png 36w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klient-grupa-azoty-police-180x180.png 180w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/div><\/div><\/div><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><div class='flex_column_table av-2n81xw-0242bde7f03b0ff49cad98b96e5fba5a sc-av_one_third av-equal-height-column-flextable'><div  class='flex_column av-2n81xw-0242bde7f03b0ff49cad98b96e5fba5a av_one_third  avia-builder-el-43  el_after_av_one_third  avia-builder-el-last  first flex_column_table_cell av-equal-height-column av-align-middle  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lpixftxy-b676394d8759a40df33349eeb40a3a7d\">\n.avia-image-container.av-lpixftxy-b676394d8759a40df33349eeb40a3a7d img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-lpixftxy-b676394d8759a40df33349eeb40a3a7d .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-lpixftxy-b676394d8759a40df33349eeb40a3a7d av-styling- avia-align-center  avia-builder-el-44  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-473 avia-img-lazy-loading-not-473 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klienci-AQUANET-300x156.jpg\" alt='' title='klienci AQUANET'  height=\"156\" width=\"300\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klienci-AQUANET-300x156.jpg 300w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klienci-AQUANET-705x367.jpg 705w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/klienci-AQUANET.jpg 730w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/div><\/div><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_4'  class='avia-section av-2gfjh0-a6bd322fad1fb77b90472334b53ffe33 main_color avia-section-large avia-no-border-styling  avia-builder-el-45  el_after_av_section  avia-builder-el-last  avia-bg-style-parallax container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-284'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lpix9mbv-fdfc5a48729ec2830025942ba3428d7d\">\n#top .av-special-heading.av-lpix9mbv-fdfc5a48729ec2830025942ba3428d7d{\npadding-bottom:0;\n}\nbody .av-special-heading.av-lpix9mbv-fdfc5a48729ec2830025942ba3428d7d .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-lpix9mbv-fdfc5a48729ec2830025942ba3428d7d .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-lpix9mbv-fdfc5a48729ec2830025942ba3428d7d av-special-heading-h2 blockquote modern-quote modern-centered  avia-builder-el-46  el_before_av_hr  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Partnerzy<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-291j30-66891528c9ef698649ece597a3148fce\">\n#top .hr.av-291j30-66891528c9ef698649ece597a3148fce{\nmargin-top:5px;\nmargin-bottom:35px;\n}\n.hr.av-291j30-66891528c9ef698649ece597a3148fce .hr-inner{\nwidth:50px;\nborder-color:#efbb20;\n}\n<\/style>\n<div  class='hr av-291j30-66891528c9ef698649ece597a3148fce hr-custom  avia-builder-el-47  el_after_av_heading  el_before_av_one_third  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-fat'><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div class='flex_column_table av-22afjg-2afc1590d52d32c0057b93a655c021c0 sc-av_one_third av-equal-height-column-flextable'><div  class='flex_column av-22afjg-2afc1590d52d32c0057b93a655c021c0 av_one_third  avia-builder-el-48  el_after_av_hr  el_before_av_one_third  first flex_column_table_cell av-equal-height-column av-align-middle  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1x6m98-8b169ae2941191a54541a57cdecc70d9\">\n.avia-image-container.av-1x6m98-8b169ae2941191a54541a57cdecc70d9 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-1x6m98-8b169ae2941191a54541a57cdecc70d9 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-1x6m98-8b169ae2941191a54541a57cdecc70d9 av-styling- avia-align-center  avia-builder-el-49  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-448 avia-img-lazy-loading-not-448 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/partner-xylem-300x124.png\" alt='' title='partner xylem'  height=\"124\" width=\"300\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/partner-xylem-300x124.png 300w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/partner-xylem.png 349w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/div><\/div><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-1t1b98-696f4f59fea95f0b887c766b596ecf4e av_one_third  avia-builder-el-50  el_after_av_one_third  el_before_av_one_third  flex_column_table_cell av-equal-height-column av-align-middle  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1lqo0c-a621d1f9bc054d25aa164302332b45c8\">\n.avia-image-container.av-1lqo0c-a621d1f9bc054d25aa164302332b45c8 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-1lqo0c-a621d1f9bc054d25aa164302332b45c8 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-1lqo0c-a621d1f9bc054d25aa164302332b45c8 av-styling- avia-align-center  avia-builder-el-51  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-445 avia-img-lazy-loading-not-445 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/partner-ozonia-300x112.png\" alt='' title='partner ozonia'  height=\"112\" width=\"300\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/partner-ozonia-300x112.png 300w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/partner-ozonia.png 367w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/div><\/div><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-1hhrdo-8277e6bec7d6fe1d3b597ae6ded26dfe av_one_third  avia-builder-el-52  el_after_av_one_third  el_before_av_one_third  flex_column_table_cell av-equal-height-column av-align-middle  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1aab3o-2f9101efa7b4ec6d3b86cc8e6728201c\">\n.avia-image-container.av-1aab3o-2f9101efa7b4ec6d3b86cc8e6728201c img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-1aab3o-2f9101efa7b4ec6d3b86cc8e6728201c .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-1aab3o-2f9101efa7b4ec6d3b86cc8e6728201c av-styling- avia-align-center  avia-builder-el-53  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-446 avia-img-lazy-loading-not-446 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/partner-suez-veolia.png\" alt='' title='partner suez veolia'  height=\"183\" width=\"275\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><div class='flex_column_table av-3su58-ad8c1799e5da2ed1ac7523bf7ab8cd15 sc-av_one_third av-equal-height-column-flextable'><div  class='flex_column av-3su58-ad8c1799e5da2ed1ac7523bf7ab8cd15 av_one_third  avia-builder-el-54  el_after_av_one_third  el_before_av_one_third  first flex_column_table_cell av-equal-height-column av-align-middle  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-x06ws-30b4e2d0dc2b022ac004f92f92d2762c\">\n.avia-image-container.av-x06ws-30b4e2d0dc2b022ac004f92f92d2762c img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-x06ws-30b4e2d0dc2b022ac004f92f92d2762c .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-x06ws-30b4e2d0dc2b022ac004f92f92d2762c av-styling- avia-align-center  avia-builder-el-55  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-443 avia-img-lazy-loading-not-443 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/partner-grundfos-300x153.png\" alt='' title='partner grundfos'  height=\"153\" width=\"300\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/partner-grundfos-300x153.png 300w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/partner-grundfos.png 314w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/div><\/div><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-p4424-8ed0ce9133ef2b097a5ed4affb1c3bc9 av_one_third  avia-builder-el-56  el_after_av_one_third  el_before_av_one_third  flex_column_table_cell av-equal-height-column av-align-middle  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jqix8-ef6ff3b16750454f0d629af8a95cfea2\">\n.avia-image-container.av-jqix8-ef6ff3b16750454f0d629af8a95cfea2 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-jqix8-ef6ff3b16750454f0d629af8a95cfea2 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-jqix8-ef6ff3b16750454f0d629af8a95cfea2 av-styling- avia-align-center  avia-builder-el-57  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-447 avia-img-lazy-loading-not-447 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/partner-wallace-tiernan-evoqua-300x81.png\" alt='' title='partner wallace tiernan evoqua'  height=\"81\" width=\"300\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/partner-wallace-tiernan-evoqua-300x81.png 300w, https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/partner-wallace-tiernan-evoqua.png 411w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/div><\/div><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-f3pis-02e2ab3e3368741abcde8518ab6d34b9 av_one_third  avia-builder-el-58  el_after_av_one_third  avia-builder-el-last  flex_column_table_cell av-equal-height-column av-align-middle  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bqql0-66e4b4bffc7d5f3fe2db0a679e97d76a\">\n.avia-image-container.av-bqql0-66e4b4bffc7d5f3fe2db0a679e97d76a img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-bqql0-66e4b4bffc7d5f3fe2db0a679e97d76a .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-bqql0-66e4b4bffc7d5f3fe2db0a679e97d76a av-styling- avia-align-center  avia-builder-el-59  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-444 avia-img-lazy-loading-not-444 avia_image ' src=\"https:\/\/aquaseen.pl\/wp-content\/uploads\/2023\/11\/partner-milton-roy.png\" alt='' title='partner milton roy'  height=\"172\" width=\"293\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div><\/div><!--close column table wrapper. Autoclose: 1 -->\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_4'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-284'><div class='entry-content-wrapper clearfix'>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-284","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/aquaseen.pl\/index.php\/wp-json\/wp\/v2\/pages\/284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquaseen.pl\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aquaseen.pl\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aquaseen.pl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aquaseen.pl\/index.php\/wp-json\/wp\/v2\/comments?post=284"}],"version-history":[{"count":85,"href":"https:\/\/aquaseen.pl\/index.php\/wp-json\/wp\/v2\/pages\/284\/revisions"}],"predecessor-version":[{"id":1046,"href":"https:\/\/aquaseen.pl\/index.php\/wp-json\/wp\/v2\/pages\/284\/revisions\/1046"}],"wp:attachment":[{"href":"https:\/\/aquaseen.pl\/index.php\/wp-json\/wp\/v2\/media?parent=284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}